
{"id":1916,"date":"2020-07-09T13:24:37","date_gmt":"2020-07-09T12:24:37","guid":{"rendered":"https:\/\/interrailplanner.com\/blog\/?p=1916"},"modified":"2022-08-10T11:07:32","modified_gmt":"2022-08-10T10:07:32","slug":"the-ultimate-guide-to-the-glacier-express-in-switzerland","status":"publish","type":"post","link":"https:\/\/interrailplanner.com\/blog\/it\/la-guida-definitiva-al-glacier-express-in-svizzera\/","title":{"rendered":"La guida definitiva al Glacier Express in Svizzera"},"content":{"rendered":"<p>Siete alla ricerca di un incredibile viaggio in treno, diverso da tutti gli altri? Allora perch\u00e9 non salire a bordo del Glacier Express. Un viaggio magico vi attende durante questo viaggio di 8 ore attraverso la Svizzera. Definito il treno espresso pi\u00f9 lento del mondo, i panorami mozzafiato che vedrete durante questo viaggio vi lasceranno senza fiato.<\/p><div class=\"inter-content-paragraph\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-3534407402\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p>La Svizzera \u00e8 da tempo una delle mete preferite di <a href=\"https:\/\/interrailplanner.com\/blog\/where-should-i-go-interrailing-in-switzerland-the-top-5-places-to-interrail-in-switzerland\/\" class=\"rank-math-link\">interrailers<\/a> grazie alle sue imponenti montagne innevate, al cibo delizioso e all'atmosfera accogliente. Ma se volete vederla in modo straordinario, il viaggio con il Glacier Express \u00e8 la scelta migliore.<\/p><figure class=\"wp-block-embed-instagram wp-block-embed is-type-rich is-provider-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CCa6cmunNJp\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CCa6cmunNJp\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewbox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Visualizza questo post su Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CCa6cmunNJp\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Un post condiviso da Interrail Planner (@interrailplanner)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure><h2 class=\"wp-block-heading\" id=\"what-s-the-route-of-the-glacier-express\"><strong>Qual \u00e8 il percorso del Glacier Express?<\/strong><\/h2><p>Il Glacier Express effettua il seguente percorso:<\/p><div class=\"inter-content_2\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-3076182091\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p><strong>Zermatt<\/strong> &gt; <strong>Briga<\/strong> &gt; <strong>Andermatt<\/strong> &gt; <strong>Disentis<\/strong> &gt; <strong>Coira<\/strong> &gt; <strong>Castello di legno<\/strong> &gt; <strong>Filisure<\/strong> &gt; <strong>Samedan<\/strong> &gt; <strong>Moritz<\/strong><\/p><p>Lungo i 180 chilometri del percorso, passerete sotto ben 291 ponti e 91 gallerie. Non solo, ma potrete ammirare il Grand Canyon svizzero (Gola del Reno), pittoreschi villaggi alpini e un'abbondanza di vigneti. Osservate le carrozze panoramiche in vetro mentre ascoltate i commenti, sorseggiate un bicchiere di vino e rilassatevi.<\/p><h2 class=\"wp-block-heading\" id=\"what-s-the-train-like\"><strong>Com'\u00e8 il treno?<\/strong><\/h2><p>Il Glacier Express \u00e8 un treno davvero confortevole che offre carrozze di 1a e 2a classe circondate da vetrate panoramiche. Sebbene la 1a classe sia ovviamente pi\u00f9 costosa, l'unica vera differenza \u00e8 che ha pi\u00f9 spazio. Quindi, se volete risparmiare un po', la seconda classe \u00e8 altrettanto meravigliosa.&nbsp;<\/p><p>A bordo sono presenti un bar e un ristorante. Servono spuntini, pasti e bevande e vi permetteranno di godervi un momento favoloso ammirando il panorama circostante. <br><\/p><figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/B6gPMP3ouA_\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/B6gPMP3ouA_\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewbox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Visualizza questo post su Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/B6gPMP3ouA_\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Un post condiviso da Living Destinations (@living_destinations)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure><h2 class=\"wp-block-heading\" id=\"how-much-does-the-glacier-express-cost\"><strong>Quanto costa il Glacier Express?<\/strong><\/h2><p>Una delle cose pi\u00f9 importanti che vi starete chiedendo \u00e8 quanto vi coster\u00e0 il Glacier Express. A causa della lunghezza e del lusso che questo viaggio comporta, non \u00e8 certo il pi\u00f9 economico.<\/p><p><strong>Una tariffa base da Zermatt a St Moritz vi coster\u00e0 un bel po':<\/strong><\/p><ul class=\"wp-block-list\"><li><strong>152 CHF (\u00a3129) in 2a classe per la sola andata<\/strong><\/li><li><strong>268 CHF (\u00a3228) 1a classe per la sola andata<\/strong><\/li><\/ul><p>Per la classe Glacier Express Excellence, dovrete mettere in conto circa 420 CHF (357 sterline), indipendentemente dalla stagione.<\/p><p>Questi prezzi sono soggetti a variazioni e non includono il costo della prenotazione, che \u00e8 di:<\/p><ul class=\"wp-block-list\"><li><strong>43 CHF (36\u20ac) giugno-settembre, solo andata<\/strong><\/li><li><strong>33 CHF (28\u20ac) Primavera e autunno&nbsp;<\/strong><\/li><li><strong>23 CHF (19\u20ac) Inverno<\/strong><\/li><\/ul><p><strong>Per il Glacier Express Excellence \u00e8 previsto il pagamento di un diritto di prenotazione di:<\/strong><\/p><ul class=\"wp-block-list\"><li><strong>420 CHF (357\u20ac)<\/strong>)<\/li><\/ul><p><strong>In questo modo \u00e8 possibile sfruttare i seguenti vantaggi:<\/strong><\/p><ul class=\"wp-block-list\"><li><strong>Un posto garantito alla finestra<\/strong><\/li><li><strong>Un concierge&nbsp;<\/strong><\/li><li><strong>Trasporto bagagli<\/strong><\/li><li><strong>Welcome-desk e check-in personale sulla piattaforma<\/strong><\/li><li><strong>Un tablet da utilizzare a bordo&nbsp;<\/strong><\/li><li><strong>Accesso esclusivo al Glacier Bar di bordo<\/strong><\/li><\/ul><p><strong>Anche il catering \u00e8 stato potenziato, offrendo:<\/strong><\/p><ul class=\"wp-block-list\"><li><strong>Aperitivo e amuse-bouche<\/strong><\/li><li><strong>Un pasto di 5 portate (stagionale) con vino di accompagnamento<\/strong><\/li><li><strong>Caff\u00e8, succo di frutta, champagne e brioche<\/strong><\/li><li><strong>Caff\u00e8 e digestivo con cioccolatini<\/strong><\/li><\/ul><p>Se si desidera pranzare sul Glacier Express (non sull'Excellence), anche questo \u00e8 un costo aggiuntivo e si aggira in media intorno a quanto segue:<\/p><ul class=\"wp-block-list\"><li><strong>30 CHF ( \u00a325 ) per la specialit\u00e0 del giorno<\/strong><\/li><li><strong>43 CHF (36\u20ac) per un piatto di tre portate.<\/strong>l<\/li><\/ul><figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"315\" src=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/07\/glacier-express-1337247_640.jpg\" alt=\"Il Glacier Express in Svizzera\" class=\"wp-image-1922\" srcset=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/07\/glacier-express-1337247_640.jpg 640w, https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/07\/glacier-express-1337247_640-600x295.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption>Immagine da&nbsp;<a href=\"https:\/\/pixabay.com\/users\/hpgruesen-2204343\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=1337247\" target=\"_blank\" rel=\"noopener\">Erich Westendarp<\/a>&nbsp;da&nbsp;<a href=\"https:\/\/pixabay.com\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=1337247\" target=\"_blank\" rel=\"noopener\">Pixabay<\/a>&nbsp;<\/figcaption><\/figure><h2 class=\"wp-block-heading\" id=\"when-should-i-take-the-glacier-express\"><strong>Quando prendere il Glacier Express?<\/strong><\/h2><p>Il viaggio con il Glacier Express \u00e8 meraviglioso in qualsiasi momento. Tuttavia, in inverno \u00e8 possibile ammirare le splendide montagne innevate, rendendo il viaggio ancora pi\u00f9 magico. Ma per avere una vista pi\u00f9 chiara e quasi garantita, la primavera \u00e8 la scelta migliore.<\/p><p>Tenete presente che il Glacier Express funziona quasi tutto l'anno, con una pausa tra fine ottobre e met\u00e0 dicembre. Pertanto, \u00e8 importante controllare l'orario del <a href=\"https:\/\/www.glacierexpress.ch\/en\/travel-planning\/timetables\/\" target=\"_blank\" rel=\"noopener\">orario<\/a> per assicurarsi di poter viaggiare quando si vuole. <\/p><h2 class=\"wp-block-heading\" id=\"how-to-book-tickets\"><strong>Come prenotare i biglietti<\/strong><\/h2><p>La prenotazione dei biglietti per il Glacier Express \u00e8 nota per essere piuttosto impegnativa. Per questo motivo, prima di iniziare il processo, \u00e8 bene saperne un po' di pi\u00f9. Quando acquistate i biglietti per il vostro viaggio, dovrete pagare una tassa di prenotazione obbligatoria insieme al prezzo base del biglietto.&nbsp;<\/p><p>Il costo del biglietto base dipende da diversi fattori, tra cui la scelta della prima o della seconda classe e la distanza percorsa. In quest'ultimo caso, non \u00e8 necessario percorrere tutto il tragitto da Zermatt a St Moritz. Potrete invece scegliere di scendere in una delle destinazioni lungo il percorso.<\/p><p>Quando si accede al sito, \u00e8 possibile accedere alla sezione '<a href=\"https:\/\/shop.glacierexpress.ch\/gex_en\/specials\/daytrips\" target=\"_blank\" rel=\"noopener\">gite di un giorno<\/a>'. Da qui, \u00e8 possibile scegliere tra le opzioni <a href=\"https:\/\/shop.glacierexpress.ch\/gex_en\/specials\/daytrips\/glacier-express\" target=\"_blank\" rel=\"noopener\">Ghiacciaio Espresso <\/a>o il <a href=\"https:\/\/shop.glacierexpress.ch\/gex_en\/specials\/daytrips\/glacier-express-excellence-class\" target=\"_blank\" rel=\"noopener\">Glacier Express Classe Excellence<\/a>. Vi verr\u00e0 quindi chiesto di inserire le date desiderate e la tratta - tenete presente che anche se potete pagare la tassa di prenotazione, non potete prenotare i biglietti fino a 2 mesi prima.<\/p><p>Quindi, \u00e8 possibile scegliere tra diversi orari di viaggio. Una volta selezionato, si pu\u00f2 decidere dove sedersi sul treno. Il bello del Glacier Express \u00e8 che pu\u00f2 essere reso pi\u00f9 accessibile.<\/p><p>Come? Perch\u00e9 potrete inserire dettagli che riducono il prezzo del biglietto. Questi includono:<\/p><ul class=\"wp-block-list\"><li><strong>Abbonamento a met\u00e0 prezzo<\/strong><\/li><li><strong>Carta di viaggio per giovani o nipoti<\/strong><\/li><li><strong>Biglietto da viaggio GA<\/strong><\/li><li><strong>Bambini fino a 6 anni<\/strong><\/li><li><strong>Passaggio di 1 giorno per l'abbonamento a met\u00e0 prezzo&nbsp;<\/strong><\/li><li><strong>Travelpass di 1 giorno per bambini<\/strong><\/li><li><strong>Scheda famiglia STS<\/strong><\/li><li><strong>Railcard<\/strong><\/li><li><strong>Carta met\u00e0-prezzo Svizzera e Carta met\u00e0-prezzo Combi<\/strong><\/li><li><strong>Swiss Travel Pass (Flex, Youth, Youth-Flex)<\/strong><\/li><li><strong>Biglietto per il trasferimento in Svizzera<\/strong><\/li><li><strong>Biglietto di trasferimento svizzero su Transferdays e Combi<\/strong><\/li><li><strong>Eurail\/ <\/strong><a href=\"https:\/\/interrailplanner.com\/blog\/which-countries-can-you-interrail-in-map-of-participating-interrail-countries-and-national-rail-companies\/\"><strong>Pass Interrail<\/strong><\/a><\/li><\/ul><p>Oltre ad approfittare delle promozioni, potete risparmiare anche viaggiando in bassa stagione. Poich\u00e9 i costi di prenotazione cambiano a seconda del periodo dell'anno, potreste scegliere un periodo (ad esempio dicembre) in cui i prezzi sono molto pi\u00f9 bassi. In questo modo, potrete risparmiare denaro che potrete spendere per un pasto delizioso durante il viaggio o per un'altra parte del vostro viaggio in Svizzera.<\/p><h2 class=\"wp-block-heading\" id=\"tips-for-your-glacier-express-trip\"><strong>Consigli per il vostro viaggio sul Glacier Express <\/strong><\/h2><figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"640\" height=\"442\" src=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/07\/bernina-pass-1272822_640.jpg\" alt=\"\" class=\"wp-image-1928\" srcset=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/07\/bernina-pass-1272822_640.jpg 640w, https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/07\/bernina-pass-1272822_640-600x414.jpg 600w, https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/07\/bernina-pass-1272822_640-300x207.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption>Immagine da&nbsp;<a href=\"https:\/\/pixabay.com\/users\/hpgruesen-2204343\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=1272822\" target=\"_blank\" rel=\"noopener\">Erich Westendarp<\/a>&nbsp;da&nbsp;<a href=\"https:\/\/pixabay.com\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=1272822\" target=\"_blank\" rel=\"noopener\">Pixabay<\/a>&nbsp;<\/figcaption><\/figure><h3 class=\"wp-block-heading\" id=\"save-money-through-travelling-2nd-class\"><strong>Risparmiare denaro viaggiando in 2a classe<\/strong><\/h3><p>Anche se \u00e8 bello poter dire di aver viaggiato in 1a classe, l'unica differenza \u00e8 lo spazio in pi\u00f9. Quindi, se volete risparmiare, optate per l'opzione pi\u00f9 economica. <\/p><h3 class=\"wp-block-heading\" id=\"it-doesn-t-really-matter-which-seat-you-re-in\"><strong>Non importa quale sia il posto in cui ci si trova.<\/strong><\/h3><p>Anche se molte persone si contenderanno i posti al finestrino, potrete godere di una vista fantastica da tutti i posti grazie ai finestrini panoramici delle carrozze. Quindi non stressatevi! Trovate semplicemente un posto libero sul sito di prenotazione e partite da l\u00ec.<\/p><h3 class=\"wp-block-heading\" id=\"book-as-soon-as-you-can\"><strong>Prenotate il prima possibile<\/strong><\/h3><p>Anche se non \u00e8 possibile pagare la tariffa base fino a 2 mesi prima, vale la pena prenotare il prima possibile. Infatti, se lo desiderate, potete prenotare fino a 93 giorni prima. Il Glacier Express \u00e8 incredibilmente popolare, quindi non perdete l'occasione di goderne.<\/p><div class=\"inter-after-content\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-1023166959\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"8015293915\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Siete alla ricerca di un incredibile viaggio in treno, diverso da tutti gli altri? Allora perch\u00e9 non salire a bordo del Glacier Express. Un viaggio magico vi attende durante questo viaggio di 8 ore attraverso la Svizzera. Definito il treno espresso pi\u00f9 lento del mondo, i panorami mozzafiato che vedrete durante questo viaggio vi lasceranno senza fiato. La Svizzera \u00e8 stata a lungo...<\/p>","protected":false},"author":26,"featured_media":3498,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13],"tags":[59,193],"class_list":["post-1916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interrail-country-region-guides","tag-interrail-switzerland","tag-zermatt"],"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"jetpack_featured_media_url":"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/07\/christian-lue-lp3ht8q2SEE-unsplash.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/posts\/1916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=1916"}],"version-history":[{"count":0,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/posts\/1916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/media\/3498"}],"wp:attachment":[{"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=1916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=1916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=1916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}