
{"id":177,"date":"2016-07-17T18:46:36","date_gmt":"2016-07-17T17:46:36","guid":{"rendered":"https:\/\/209.222.30.173\/?p=177"},"modified":"2020-12-22T14:11:00","modified_gmt":"2020-12-22T14:11:00","slug":"an-interrail-adventure-blog-11-bonn","status":"publish","type":"post","link":"https:\/\/interrailplanner.com\/blog\/it\/un-blog-sullavventura-interrail-11-bonn\/","title":{"rendered":"Un'avventura Interrail - Blog 11: Bonn"},"content":{"rendered":"<p style=\"font-weight: 400;\">Arrivato a Bonn, ho affrontato il disastro che il moderno interrailer spera di non dover mai sopportare: le mappe del mio telefono si erano rotte! Con il mio grande zaino, mi trovavo a vagare per una citt\u00e0 straniera senza alcuna idea. Tuttavia, avevo le indicazioni per la stazione ferroviaria e per l'ostello sul mio telefono: era giunto il momento di seguire un po' la vecchia scuola e di seguire religiosamente queste indicazioni, piuttosto che creare il mio percorso. Ebbene, sarete felici di sapere che dopo aver sbagliato, essere tornata sui miei passi e aver ricominciato un paio di volte, alla fine ce l'ho fatta!<\/p><div class=\"inter-content-paragraph\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-1431410777\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"font-weight: 400;\">Dopo aver cucinato, pulito e sistemato in generale, cosa mi restava da fare? Oh, lo so, girare per la citt\u00e0! Camminando nel centro della citt\u00e0, mi sono subito resa conto che Bonn ha dato i natali a Ludwig Van Beethoven, una fama piuttosto impressionante. \u00c8 stata anche la capitale della Germania Ovest per un periodo, un'altra cosa interessante. Sempre in tema di democrazia, Bonn aveva anche una sede e un campus delle Nazioni Unite, raggiungibili con una passeggiata lungo il Reno. Ho deciso di fare questa passeggiata, ma si \u00e8 rivelata un'impresa ardua. Ma alla fine ci sono arrivato e mi sono prontamente girato per tornare indietro lungo il Reno. Un tranquillo campus dell'ONU di sera non \u00e8 molto eccitante, ma lungo il fiume c'era una versione in scala del Sistema Solare, piuttosto interessante.<\/p>\n<p style=\"font-weight: 400;\">Il mio ostello si trovava nella parte vecchia della citt\u00e0 (altstadt), quindi, tornando in questa zona, decisi di andare da qualche parte, prendere un drink tranquillo e poi tornare all'ostello. Girovagando, ho scelto un pub all'angolo, ma poi ho scoperto che non era tranquillo. In qualche modo avevo trovato un incontro settimanale di danza latina, nello spazio eventi del pub. Ora, io non sono brava in questo tipo di ballo - posso ballare alla discoteca silenziosa - quindi mi sono accontentata di sedermi, guardare e godermi la musica. Alla fine sono riuscita a chiacchierare con un ragazzo del posto, che mi ha spiegato da quanto tempo si tenevano gli incontri e perch\u00e9 si svolgevano. Il momento forse pi\u00f9 bello della serata \u00e8 stato quando, appena tornata dal bagno, \u00e8 arrivato un collega inglese, un frequentatore abituale dell'incontro di danza. Stava chiacchierando con qualcuno in inglese. Ora, la mia voce rivela abbastanza rapidamente la mia nazionalit\u00e0, quindi inizialmente sono rimasta in silenzio. Quando ho parlato, la sua faccia \u00e8 stata fantastica: una vera e propria doppia espressione facciale, quando ha capito che non ero tedesco, ma inglese. Abbiamo chiacchierato un po' di viaggi e di Bonn, poi alla fine la serata si \u00e8 conclusa. Con qualche Weissbier in corpo, ho ritrovato la strada per l'ostello, perdendomi solo una volta!<\/p><div class=\"inter-content_2\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-523660857\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"font-weight: 400;\">Dopo un risveglio e una colazione un po' lenti, il giorno dopo ho lasciato l'ostello pronta a vedere di pi\u00f9 della citt\u00e0. L'inglese dell'incontro di danza mi aveva raccomandato il museo della Deutsche e il castello, quindi erano sulla mia lista. A parte questo, la giornata era completamente libera. Girovagando, ho visitato l'universit\u00e0, i giardini botanici, la casa di Beethoven e il centro della citt\u00e0. Ho visto il castello, o almeno ci\u00f2 che ne rimaneva. Non vorrei sembrare una snob dei castelli, ma non sono rimasta molto colpita.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/f5aakDBhdkPyzEshZ6q-xqJcQ6r8XjbQOYiU9Ckf1-G0VlSmt38FzFWPyiYqYHnQUO6WE4P2B11zqah3of4fmNaBouT4KalhB5V02zUtWUzRldpqmzO0LZJ9kDM4bEA7KB7q1KQc\" alt=\"\" width=\"1600\" height=\"900\"><figcaption class=\"wp-caption-text\">I giardini botanici di Bonn<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">Quel pomeriggio \u00e8 arrivato il Deutsche Museum - per un laureato in scienze come me, \u00e8 stato incredibile! Il museo aveva riunito una serie di oggetti che mostravano i contributi tedeschi alla scienza e alla tecnologia nel corso degli anni. Inoltre, metteva in evidenza alcuni degli effetti politici sulla scienza nel corso degli anni in Germania. Mi sono resa conto in seguito che questo museo non era quello di cui mi avevano parlato, ma che c'era un altro museo tedesco in un'altra parte della citt\u00e0, ma non mi importava. Questo museo era cos\u00ec bello! Tornando in citt\u00e0, mi sono imbattuta in una galleria d'arte con una mostra fotografica intitolata \"Enjoy your life\". Pensando che si sarebbe trattato di una serie di scatti piacevoli e positivi per la vita, ho comprato un biglietto e sono entrata. Beh, le foto erano in un certo senso positive per la vita, solo che c'era molta pi\u00f9 nudit\u00e0 di quanto mi aspettassi. \u00c8 stato interessante e valeva la pena andarci, ma non dimenticher\u00f2 lo shock iniziale quando ho capito cosa mostrava davvero questa mostra. Oh, e c'erano piatti ammucchiati in tutta la sala espositiva - era in relazione alle foto, ma ho passato tutto il tempo con il terrore di farli cadere!<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/AiY58DS2NbvTvRRzfdn4uWamUjbkxc4UiIDkSZ7MDXAfWwv9K-QKweLcnaICpxXz25yOpukRos6fYmRYMS3XHwBTeFtPtMjYebUb8OfJ3WWfsb07orv_tSYssy4BZ72p5NYxsiZ7\" alt=\"\" width=\"1600\" height=\"900\"><figcaption class=\"wp-caption-text\">La piazza del mercato di Bonn<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">Dopo una giornata faticosa, ho passato la serata a rilassarmi nel centro della citt\u00e0. Ho preso un gelato e ho passeggiato lentamente, \u00e8 stato bello e rilassante. Quella notte ho dormito molto facilmente! Questa mattina ho avuto la possibilit\u00e0 di decidere quando prendere il treno per Colonia, dato che ce n'era uno ogni ora. Cos\u00ec, ho preso un caff\u00e8 in un bar del centro e ho guardato il mondo (e la pioggia) passare. Non pensavo che Bonn sarebbe stata cos\u00ec movimentata! Speriamo che Colonia possa offrire di pi\u00f9!<\/p>\n<p style=\"font-weight: 400;\"><i><a href=\"https:\/\/twitter.com\/jackmanjames26\" target=\"_blank\" rel=\"noopener\">James Jackman<\/a> condivider\u00e0 le storie del suo viaggio Interrail ogni giorno per tutto il mese di giugno e luglio - seguiteci su <\/i><i><a href=\"https:\/\/www.facebook.com\/interrailplanner\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a><\/i><i> e <\/i><i><a href=\"https:\/\/twitter.com\/planinterrail\" target=\"_blank\" rel=\"noopener\">Twitter<\/a><\/i><i> per seguire i suoi aggiornamenti non appena vengono pubblicati!<\/i><\/p>\n<div class=\"inter-after-content\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-474115415\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"8015293915\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Arrivato a Bonn, ho affrontato il disastro che il moderno interrailer spera di non dover mai sopportare: le mappe del mio telefono si erano rotte! Con il mio grande zaino, mi trovavo a vagare per una citt\u00e0 straniera senza alcuna idea. Tuttavia, avevo le indicazioni per la stazione ferroviaria e l'ostello sul mio telefono -...<\/p>","protected":false},"author":6,"featured_media":616,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[33],"class_list":["post-177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interrail-adventures","tag-interrail-germany"],"cc_featured_image_caption":{"caption_text":false,"source_text":false,"source_url":false},"jetpack_featured_media_url":"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2019\/08\/interrail-adventure-bonn.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/posts\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":0,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/posts\/177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/media\/616"}],"wp:attachment":[{"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}