
{"id":399,"date":"2018-08-09T14:46:45","date_gmt":"2018-08-09T13:46:45","guid":{"rendered":"https:\/\/209.222.30.173\/?p=399"},"modified":"2020-12-22T13:48:53","modified_gmt":"2020-12-22T13:48:53","slug":"considering-a-solo-interrail-trip-top-tips-for-interrailing-around-europe-on-your-own","status":"publish","type":"post","link":"https:\/\/interrailplanner.com\/blog\/fr\/envisager-un-voyage-interrail-en-solo-conseils-pour-parcourir-leurope-en-solo\/","title":{"rendered":"Vous envisagez de faire un voyage Interrail en solo ? Conseils pour parcourir l'Europe en solo"},"content":{"rendered":"<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Mon premier contact avec le voyage en solo est le film <\/span><i><span style=\"font-weight: 400;\">Avant le coucher du soleil<\/span><\/i><span style=\"font-weight: 400;\"> o\u00f9 le beau Ethan Hawke convainc une inconnue, la belle Julie Delphi, de sauter du train et de passer la journ\u00e9e \u00e0 Vienne avec lui.<\/span><\/p><div class=\"inter-content-paragraph\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-248379840\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Malheureusement, mon aventure en solitaire n'a pas vraiment ressembl\u00e9 \u00e0 cela. Il y a eu beaucoup de sauts dans les trains. Mais c'\u00e9tait uniquement parce que je m'\u00e9tais endormie et que j'avais manqu\u00e9 mon arr\u00eat. Voici quelques-unes des choses que j'aurais aim\u00e9 savoir avant de partir \u00e0 l'aventure en solo.<\/span><\/p>\n<h4 style=\"font-weight: 400;\"><b>Choisir des auberges sociales<\/b><\/h4>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ce sont les meilleurs endroits pour commencer \u00e0 rencontrer des gens, car ils sont remplis de voyageurs partageant les m\u00eames id\u00e9es et se lan\u00e7ant dans la m\u00eame aventure que vous. Au d\u00e9but, j'ai fait l'erreur de choisir des endroits ennuyeux et st\u00e9riles, sans \u00e9nergie, et j'ai eu du mal \u00e0 me faire de bons amis. Privil\u00e9giez les auberges dont les commentaires sont \u00e9logieux sur l'atmosph\u00e8re sociale ou qui organisent leurs propres \u00e9v\u00e9nements sociaux, comme des d\u00eeners gratuits ou des excursions d'une journ\u00e9e. Vous n'obtiendrez certainement pas un repas 5 \u00e9toiles, mais ces \u00e9v\u00e9nements sont les meilleures occasions d'engager la conversation avec des inconnus et de nouer des liens autour de p\u00e2tes mal cuites.<\/span><\/p><div class=\"inter-content_2\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-1164301733\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Points bonus si l'auberge dispose d'une salle commune ou d'un bar o\u00f9 les gens se retrouvent. Allez vraiment vous promener dans ces espaces communs. Toute l'ambiance du monde ne changera rien si vous ne faites que rester dans votre chambre.<\/span><\/p>\n<h4 style=\"font-weight: 400;\"><b>V\u00e9rifiez trois fois vos heures de d\u00e9part<\/b><\/h4>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Et m\u00eame si vous \u00eates s\u00fbr de conna\u00eetre tous les d\u00e9tails, v\u00e9rifiez encore une fois. Les gares ferroviaires et routi\u00e8res sont souvent des endroits tr\u00e8s fr\u00e9quent\u00e9s et d\u00e9routants. Surtout s'il s'agit d'un pays dont vous ne connaissez pas la langue. Certaines grandes villes ont au moins deux a\u00e9roports et plusieurs grandes gares routi\u00e8res. Si vous ne faites pas attention, vous risquez d'arriver \u00e0 la mauvaise gare et de n'avoir aucun moyen pratique (et bon march\u00e9) de prendre votre train \u00e0 temps.<\/span><\/p>\n<h4 style=\"font-weight: 400;\"><b>Tenez vos projets en haleine<\/b><\/h4>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Oui, vous devez avoir une id\u00e9e de l'endroit o\u00f9 vous voulez aller et de ce que vous voulez faire. Mais cela ne doit pas \u00eatre compl\u00e8tement fig\u00e9. Des festivals ont lieu. Des march\u00e9s apparaissent. Les colocataires vous invitent \u00e0 une excursion d'une journ\u00e9e dans d'autres villes. Ne vous accrochez pas \u00e0 votre itin\u00e9raire parfaitement planifi\u00e9 au point de passer \u00e0 c\u00f4t\u00e9 de tout ce que la ville a \u00e0 vous offrir.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Vous pouvez pr\u00e9voir toutes les calamit\u00e9s du monde, les choses tourneront toujours mal. Les accidents de la circulation vous font manquer votre bus. Les trains tombent en panne. Les compagnies a\u00e9riennes \u00e0 bas prix surbookent les vols et vous font sprinter d'un c\u00f4t\u00e9 \u00e0 l'autre de l'a\u00e9roport (histoire vraie). Vous rencontrerez des gens et tomberez amoureux d'endroits qui vous feront s\u00e9rieusement envisager de d\u00e9chirer votre billet de retour. Vous vous entendrez si bien avec un habitant qu'il vous demandera de rester un jour de plus. Je me souviens d'avoir planifi\u00e9 m\u00e9ticuleusement tout mon voyage, avant d'en abandonner la moiti\u00e9 et de rentrer \u00e0 Budapest. C'\u00e9tait encore mieux la deuxi\u00e8me fois. Essayez de laisser la spontan\u00e9it\u00e9 prendre le dessus et de vous laisser porter par ce qui se passe.<\/span><\/p>\n<h4 style=\"font-weight: 400;\"><b>Faire semblant jusqu'\u00e0 ce qu'on y arrive<\/b><\/h4>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Personne ne sait litt\u00e9ralement ce qu'il fait. Tout le monde improvise et se d\u00e9brouille au fur et \u00e0 mesure. Souriez, d\u00e9tendez-vous et ayez l'air accessible. Ne r\u00e9fl\u00e9chissez pas trop. Personne ne vous regarde et ne pense que vous \u00eates triste parce que vous mangez seul. Assumez-le. Au fur et \u00e0 mesure que vous rencontrerez des gens et que vous vous ouvrirez \u00e0 eux, vous d\u00e9couvrirez que tout le monde est aussi perdu que vous. Vous ferez des erreurs et r\u00e9aliserez que vous auriez d\u00fb emporter plus de v\u00eatements et moins de maquillage. Riez et passez \u00e0 autre chose. Dites gentiment \u00e0 votre anxi\u00e9t\u00e9 d'aller se faire voir et de vous retrouver \u00e0 la maison. En fait, ne l'emmenez m\u00eame pas avec vous.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Vous pouvez \u00eatre seul et cela ne vous tuera pas. Permettez-moi de le r\u00e9p\u00e9ter pour les personnes au fond. Vous pouvez \u00eatre seul et cela ne vous tuera pas. Vous n'\u00eates pas oblig\u00e9 de vous faire des amis dans tous les endroits que vous visitez. Ne vous forcez pas \u00e0 fr\u00e9quenter des personnes avec lesquelles vous n'avez pas d'affinit\u00e9s. Acceptez de vous sentir seul, car ces sentiments se reproduiront \u00e0 l'infini. Mais vous finirez par en apprendre beaucoup sur ce que vous aimez et sur qui vous \u00eates. Vous d\u00e9couvrez les parties de vous-m\u00eame que vous avez l'habitude d'enfouir en compagnie d'autres personnes. Il y a quelque chose d'incroyablement attirant chez quelqu'un qui peut \u00eatre seul et qui n'a pas besoin de la compagnie de quelqu'un d'autre.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Il n'est pas n\u00e9cessaire de passer chaque jour \u00e0 visiter toutes les attractions touristiques. Vous en aurez probablement assez de devoir toujours faire la m\u00eame conversation avec les gens. Prenez le temps de vous d\u00e9tendre et de faire ce que vous aimez. J'ai ador\u00e9 trouver des librairies avec des caf\u00e9s pour pouvoir m'asseoir, lire et gribouiller des cartes postales. Pensez \u00e0 vous offrir une chambre priv\u00e9e pour une nuit afin de recharger vos batteries. Vous appr\u00e9cierez le calme et une bonne nuit de sommeil. \u00c0 la fin de mon voyage, j'\u00e9tais tellement fatigu\u00e9e par toutes les activit\u00e9s sociales et les visites touristiques que j'ai pass\u00e9 mes derniers jours \u00e0 camper dans la salle commune de l'auberge en regardant Netflix. \u00c9coutez votre corps et faites ce que vous avez \u00e0 faire. <\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Si vous h\u00e9sitez encore \u00e0 vous aventurer seul, ou si vous \u00eates nerveux \u00e0 l'id\u00e9e d'un voyage en solitaire, <\/span><b>s'engager simplement<\/b><span style=\"font-weight: 400;\">. Achetez votre billet. Faites votre valise. Respirez et d\u00e9tendez-vous. Tout se passera comme pr\u00e9vu.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Et m\u00eame si les choses tournent mal, vous aurez au moins une histoire dr\u00f4le \u00e0 raconter lorsque vous rentrerez chez vous.<\/span><\/p>\n<p><em><span style=\"font-weight: 400;\">Ashley Chow est \u00e9crivain \u00e0 Melbourne, en Australie. Vous pouvez trouver plus de ses mots \u00e0 l'adresse suivante <a href=\"https:\/\/www.ashchow.com\/\" target=\"_blank\" rel=\"noopener\">www.ashchow.com<\/a>.<\/span><\/em><\/p>\n<div class=\"inter-after-content\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-1733052060\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"8015293915\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Mon premier contact avec le voyage en solo remonte au film Before Sunset, dans lequel le s\u00e9duisant Ethan Hawke convainc une inconnue, la belle Julie Delphi, de sauter du train et de passer la journ\u00e9e \u00e0 Vienne avec lui. Malheureusement, ma propre aventure en solo n'a pas vraiment ressembl\u00e9 \u00e0 cela. Il y a eu beaucoup de sauts de train. Mais...<\/p>","protected":false},"author":20,"featured_media":569,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interrail-advice"],"cc_featured_image_caption":{"caption_text":"","source_text":"Credit: Lucille Marnelli via Pixabay","source_url":"https:\/\/pixabay.com\/users\/lucillemarnelli-3587899\/"},"jetpack_featured_media_url":"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2019\/08\/interrailing-solo.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=399"}],"version-history":[{"count":0,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/media\/569"}],"wp:attachment":[{"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}