
{"id":294,"date":"2018-01-08T19:03:51","date_gmt":"2018-01-08T19:03:51","guid":{"rendered":"https:\/\/209.222.30.173\/?p=294"},"modified":"2020-12-22T13:49:51","modified_gmt":"2020-12-22T13:49:51","slug":"new-year-new-interrail-planner","status":"publish","type":"post","link":"https:\/\/interrailplanner.com\/blog\/fr\/nouvelle-annee-nouveau-planificateur-interrail\/","title":{"rendered":"Nouvelle ann\u00e9e, nouveau planificateur Interrail"},"content":{"rendered":"<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Apr\u00e8s quelques mois de dur labeur de d\u00e9veloppement, nous sommes ravis d'annoncer que nous d\u00e9marrons la nouvelle ann\u00e9e avec une foule de nouvelles fonctionnalit\u00e9s ! Inspir\u00e9 par les commentaires des charmants Interrailers qui ont utilis\u00e9 Interrail Planner pour planifier leurs voyages, ainsi que par notre exp\u00e9rience de l'utilisation de notre propre site Web pour planifier des voyages, Interrail Planner est maintenant disponible en ligne. <a href=\"https:\/\/interrailplanner.com\/blog\/interrail-planner-co-founders-went-interrailing\">notre voyage de l'\u00e9t\u00e9 dernier<\/a>*, nous pensons que ces am\u00e9liorations vont faire une \u00e9norme diff\u00e9rence dans votre exp\u00e9rience de planification.<\/span><\/p><div class=\"inter-content-paragraph\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-1407700940\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Laissez-nous donc vous pr\u00e9senter les changements et les id\u00e9es qui les sous-tendent ! D\u00e9sol\u00e9 si c'est trop long, nous sommes tellement passionn\u00e9s par l'am\u00e9lioration de votre exp\u00e9rience Interrail qu'il nous arrive de nous emballer :<\/span><\/p>\n<h4 style=\"font-weight: 400;\"><b>Indiquer au planificateur quand <\/b><b><i>vous<\/i><\/b><b> vous souhaitez utiliser vos jours de voyage<\/b><\/h4>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/lh3.googleusercontent.com\/YxAzmz0eZeJpQsUGz6wWcvEf9VYRjxXh__O6uHhWObDu3PKRB8Ay2hmtgWpFuCdg8bgfO4tSser3zW_zG3SI81jAlFmWfzWTaNrpGT8Kn8uc3PaqLK_OWsJyI1Mv279zQTsQCNVG\" width=\"259\" height=\"121\"><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Les cartes Interrail sp\u00e9cifient une p\u00e9riode de validit\u00e9 et le nombre de jours pendant lesquels vous \u00eates autoris\u00e9 \u00e0 voyager en utilisant la carte au cours de cette p\u00e9riode. C'est pourquoi le planificateur Interrail a toujours \u00e9t\u00e9 dot\u00e9 d'une fonction unique de suivi des jours de voyage, qui comptabilise le nombre de jours de voyage utilis\u00e9s par un plan, ainsi que la p\u00e9riode totale au cours de laquelle ces jours de voyage sont utilis\u00e9s. Cela vous permet de vous assurer que votre voyage correspond bien \u00e0 l'abonnement Interrail que vous allez acheter.<\/span><\/p><div class=\"inter-content_2\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-3271056426\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cependant, nous avons essay\u00e9 d'\u00eatre un peu trop intelligents auparavant et nous avons fait un tas d'hypoth\u00e8ses pour d\u00e9cider si le pass serait utilis\u00e9 ou non pour un trajet particulier. Cela signifiait que si l'une de ces hypoth\u00e8ses \u00e9tait erron\u00e9e, la fonction de suivi des abonnements \u00e9tait effectivement d\u00e9sactiv\u00e9e pour ce plan.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Nous avons donc d\u00e9cid\u00e9 de rendre le pouvoir aux planificateurs ! Avec une simple case \u00e0 cocher, <\/span><b>vous pouvez maintenant d\u00e9cider d'utiliser ou non votre carte pour un trajet particulier<\/b><span style=\"font-weight: 400;\">La fonction de suivi des laissez-passer est ainsi beaucoup plus flexible. Ne vous inqui\u00e9tez pas si vous devez faire le suivi vous-m\u00eame, nous le ferons toujours.<\/span><\/p>\n<h4><b>Ajouter des escales<\/b><\/h4>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"\" src=\"https:\/\/lh4.googleusercontent.com\/A01KrWkTJ6UnZMfJCUW3POMnfPNDckt_03f8856bOmn1q04U_vSui8tH--Ek1-oXtevnwVq13ofH06HUTEzfXZ9hIekVIrxeazBAyK_VHbQgfePUqGiKL9DYaTsy_404ZXHGEBwR\" width=\"555\" height=\"112\"><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Nous recevons de nombreux commentaires positifs, mais une question revenait sans cesse : \"Pourquoi ne puis-je pas ajouter des escales ?!\"<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Les futurs Interrailers du monde entier seront heureux d'apprendre que <\/span><b>vous pouvez d\u00e9sormais ajouter des escales !<\/b><span style=\"font-weight: 400;\"> Lorsqu'une destination est fix\u00e9e \u00e0 une nuit, il suffit d'appuyer sur l'ic\u00f4ne \"-\" pour qu'elle devienne une escale, c'est-\u00e0-dire un s\u00e9jour de z\u00e9ro nuit. Les interrailers peuvent utiliser cette fonction pour ajouter des excursions d'une journ\u00e9e et des lieux qu'ils pr\u00e9voient de visiter pendant quelques heures avant de se rendre dans une autre ville pour y passer la nuit.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">En ce qui concerne le suivi de la carte ci-dessus, nous avons fait attention \u00e0 la fa\u00e7on dont les escales fonctionnent : si vous choisissez d'utiliser votre carte pour les trajets de part et d'autre d'une escale, nous ne compterons qu'un seul jour de voyage, \u00e9tant donn\u00e9 que les trajets ont lieu le m\u00eame jour.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">En outre, \u00e9tant donn\u00e9 que les trains de nuit comptent comme utilisant 1 jour de voyage le jour de l'arriv\u00e9e (voir <a href=\"https:\/\/interrailplanner.com\/blog\/how-does-the-7pm-interrailing-rule-work\">R\u00e8gle des 7 heures<\/a>), si vous avez une escale le jour qui suit un train de nuit, nous veillerons \u00e0 ne compter qu'un seul jour de voyage utilis\u00e9.<\/span><\/p>\n<h4 style=\"font-weight: 400;\"><b>Recherche de vols<\/b><\/h4>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/lh3.googleusercontent.com\/K-QHY-S4f3bGwn3fCT9J-j07wa7w6xfPqD5g27rj0G6NN5U3xZDSBtb-81Qj-gXKjY3cA9cY4zqgmGyhEcbdBFhDqBk1bgKBDwI_Axmsmq_rN6RYQxaMIC1gVAcLVFmLYlAysaP3\" width=\"409\" height=\"118\"><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Les interrailers prennent souvent l'avion pour leur premi\u00e8re destination europ\u00e9enne et le retour pour leur derni\u00e8re destination. <\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Pourquoi, me direz-vous ? L'une des raisons est qu'il n'est pas possible d'utiliser une carte Interrail pour voyager au-del\u00e0 des fronti\u00e8res de son propre pays. Il existe une exception \u00e0 cette r\u00e8gle : les voyageurs Interrail peuvent obtenir un laissez-passer Interrail pour traverser les fronti\u00e8res de leur pays. <a href=\"https:\/\/interrailplanner.com\/blog\/eurostar-fares-lowered-for-interrailers\">tarif r\u00e9duit sur l'Eurostar<\/a> en \u00e9change de l'un des pr\u00e9cieux jours de voyage de leur carte Interrail. Cependant, ce tarif r\u00e9duit est d'environ 20 livres sterling, donc si vous voyagez de Londres \u00e0 Paris, Bruxelles ou Amsterdam, il peut \u00eatre plus rentable de r\u00e9server un vol que de payer le tarif r\u00e9duit de l'Eurostar et d'utiliser un de vos pr\u00e9cieux jours de voyage.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Un autre avantage de prendre l'avion pour votre premi\u00e8re destination est que vous pouvez allonger votre voyage Interrail. Supposons que vous preniez l'avion pour Amsterdam, puis le train pour Berlin quelques jours plus tard. Votre carte Interrail ne devrait pas \u00eatre active avant le jour o\u00f9 vous vous rendez \u00e0 Berlin - dans ce sc\u00e9nario, la p\u00e9riode de validit\u00e9 de votre carte Interrail commence \u00e0 se d\u00e9compter lorsque vous <\/span><i><span style=\"font-weight: 400;\">quitter<\/span><\/i><span style=\"font-weight: 400;\"> Amsterdam, et non le jour de votre arriv\u00e9e. Cela signifie que ces jours \u00e0 Amsterdam ne doivent pas \u00eatre compt\u00e9s dans la p\u00e9riode de validit\u00e9 de votre carte Interrail. Ainsi, au lieu d'\u00eatre limit\u00e9 \u00e0 un voyage Interrail de 15 jours (par exemple), si vous prenez l'avion pour vous rendre chez vous et en revenir, votre voyage peut durer 15 jours, plus les jours pass\u00e9s dans votre premi\u00e8re destination et les jours pass\u00e9s dans votre derni\u00e8re destination. Vous pouvez acheter le m\u00eame pass Interrail, mais visiter deux villes suppl\u00e9mentaires et passer encore plus de temps en Europe.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Par cons\u00e9quent, m\u00eame si Interrail concerne traditionnellement les voyages en train, on peut affirmer sans risque de se tromper que les vols \u00e0 bas prix peuvent \u00e9galement faire partie int\u00e9grante d'Interrailing. <\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">C'est dans cette optique que nous avons mis en place les moyens suivants <\/span><b>Recherche instantan\u00e9e de vols avec Interrail Planner !<\/b><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Nous indiquons automatiquement le lieu d'origine, la destination et la date \u00e0 l'aide des d\u00e9tails du plan, puis nous vous emmenons sur le site suivant <a href=\"http:\/\/www.anrdoezrs.net\/links\/7251860\/type\/dlg\/https:\/\/www.skyscanner.net\/\" target=\"_blank\" rel=\"noopener\">Skyscanner<\/a> pour trouver les meilleurs vols pour ce trajet particulier. Il est ainsi tr\u00e8s simple pour les voyageurs Interrail de d\u00e9terminer les bonnes destinations de d\u00e9part et d'arriv\u00e9e, en fonction des horaires et des prix des vols. Vous pouvez d\u00e9j\u00e0 rechercher des h\u00e9bergements et des r\u00e9servations de si\u00e8ges sur Interrail Planner d'une mani\u00e8re tr\u00e8s similaire, ce qui vient s'ajouter \u00e0 une s\u00e9rie de fonctionnalit\u00e9s simplifiant l'exp\u00e9rience de planification d'Interrail.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Nous avons en fait lanc\u00e9 cette fonctionnalit\u00e9 \u00e0 la mi-novembre 2017, plus t\u00f4t que le reste des changements pr\u00e9sent\u00e9s dans ce billet, et notre intuition quant \u00e0 son utilit\u00e9 s'est av\u00e9r\u00e9e juste - les gens ont d\u00e9j\u00e0 r\u00e9serv\u00e9 plus de 120 vols par le biais d'Interrail Planner en 2 mois !<\/span><\/p>\n<h4 style=\"font-weight: 400;\"><b>Cacher votre destination d'origine et modifier votre destination d'arriv\u00e9e<\/b><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/lh4.googleusercontent.com\/LC-iUrkCHoj5Re027EMWfRV8NlZK7VcVAsHxE10l23EaXiVEdw16zUI_weeTld9NIjTQ-xIk5n-VaDYIvOi_6q6RGfAHucGVEPtYFiUfPRoSqkCelM4Lc0tXBwqYd04hR_Yt9WP2\" width=\"171\" height=\"122\"><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u00c0 la demande g\u00e9n\u00e9rale, nous avons offert la possibilit\u00e9 de <\/span><b>masquer votre destination d'origine sur la carte<\/b><span style=\"font-weight: 400;\">. Nous avons re\u00e7u des commentaires selon lesquels il \u00e9tait g\u00eanant d'avoir toujours les itin\u00e9raires de d\u00e9part et d'arriv\u00e9e sur la carte. Nous esp\u00e9rons que cela r\u00e9soudra ce probl\u00e8me et que vous pourrez vous concentrer sur la partie amusante du voyage.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Vous pouvez aussi maintenant <\/span><b>modifier votre destination d'arriv\u00e9e<\/b><span style=\"font-weight: 400;\">Ainsi, vous n'\u00eates plus oblig\u00e9 de rentrer chez vous si vous ne le souhaitez pas.<\/span><\/p>\n<h4 style=\"font-weight: 400;\"><b>Dites-nous ce que vous en pensez !<\/b><\/h4>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Voil\u00e0 donc les principaux changements ! Nous aimerions conna\u00eetre votre avis, alors n'h\u00e9sitez pas \u00e0 nous faire part de vos commentaires. <a href=\"https:\/\/interrailplanner.com\/contact\">prendre contact<\/a> et faites-nous part de vos commentaires. Si vous rencontrez quelque chose qui semble \u00eatre cass\u00e9 ou ne pas fonctionner, essayez de vider votre cache dans l'historique de votre navigateur, et si le probl\u00e8me persiste m\u00eame apr\u00e8s avoir fait cela, n'h\u00e9sitez pas \u00e0 nous en faire part et nous nous occuperons de le r\u00e9soudre.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Par ailleurs, nous esp\u00e9rons que le planificateur Interrail vous sera encore plus utile qu'auparavant et que vous ferez un excellent voyage Interrail !<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">*Fait amusant : utiliser son propre produit est connu sous le nom de \"dogfooding\" dans le monde de la technologie. C'est tr\u00e8s glamour !<\/span><\/p>\n<div class=\"inter-after-content\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-1989914718\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"8015293915\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s quelques mois de dur labeur de d\u00e9veloppement, nous sommes ravis d'annoncer que nous d\u00e9marrons la nouvelle ann\u00e9e avec une foule de nouvelles fonctionnalit\u00e9s ! Inspir\u00e9 par les commentaires des charmants Interrailers qui ont utilis\u00e9 Interrail Planner pour planifier leurs voyages, ainsi que par notre exp\u00e9rience de l'utilisation de notre propre site Web pour planifier notre voyage en...<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-294","post","type-post","status-publish","format-standard","hentry","category-news"],"cc_featured_image_caption":{"caption_text":false,"source_text":false,"source_url":false},"jetpack_featured_media_url":"","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=294"}],"version-history":[{"count":0,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/294\/revisions"}],"wp:attachment":[{"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}