
{"id":297,"date":"2018-01-15T20:38:51","date_gmt":"2018-01-15T20:38:51","guid":{"rendered":"https:\/\/209.222.30.173\/?p=297"},"modified":"2023-02-15T12:25:35","modified_gmt":"2023-02-15T12:25:35","slug":"where-should-i-go-interrailing-in-france-our-ultimate-interrail-route-for-travelling-around-france","status":"publish","type":"post","link":"https:\/\/interrailplanner.com\/blog\/es\/donde-viajar-en-interrail-por-francia-nuestra-ruta-interrail-definitiva-para-viajar-por-francia\/","title":{"rendered":"\u00bfPor d\u00f3nde hacer el interrail en Francia? Nuestra ruta interrail definitiva para viajar por Francia"},"content":{"rendered":"<p><i>Arnaud Schuffenecker, orgulloso franc\u00e9s, nos gu\u00eda por sus lugares favoritos de Francia.&nbsp;<\/i><i>Si quieres hacer interrail por Francia, sigue la ruta definitiva de Arnaud en Interrail por Francia con esto&nbsp;<a href=\"https:\/\/interrailplanner.com\/plan\/35940\/\">Plantilla de ruta Interrail<\/a>.<\/i><\/p><div class=\"inter-content-paragraph\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-1534494907\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p><span style=\"font-weight: 400;\">\u00bfPlaneas ir a Francia? \"Cocorico\".<\/span><\/p><p><span style=\"font-weight: 400;\">Es el destino tur\u00edstico m\u00e1s visitado del mundo, ofrece paisajes muy variados y un rico patrimonio cultural. Gracias a su red ferroviaria bien conectada y de gran calidad, d\u00e9jese tentar por un interrail por Francia. Le proponemos una ruta de Par\u00eds a Marsella. En la lista: una cena rom\u00e1ntica en Par\u00eds, un viaje al futuro en Poitiers, degustaci\u00f3n de quesos y vinos en Burdeos, surf en Biarritz, un d\u00eda soleado en la Costa Azul y mucho m\u00e1s... <\/span><\/p><div class=\"inter-content_2\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-2477679006\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p><span style=\"font-weight: 400;\">\"\u00a1Buen viaje!\"<\/span><\/p><h2 class=\"wp-block-heading\"><b>Par\u00eds, Francia<\/b><\/h2><figure class=\"wp-block-image alignnone size-large wp-image-1525\"><img decoding=\"async\" src=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2018\/01\/photo-1526893381913-e311045b8064-1024x1024.jpeg\" alt=\"\" class=\"wp-image-1525\"\/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: <a href=\"https:\/\/unsplash.com\/@edouard_grillot\" target=\"_blank\" rel=\"noopener\">Grillot Edouard<\/a><\/figcaption><\/figure><p><span style=\"font-weight: 400;\">\u00bfQu\u00e9 mejor que empezar nuestro viaje en la capital del amor y de la moda? Hay quien dice que se necesitar\u00eda toda una vida para visitar a fondo cada callej\u00f3n y recoveco de la ciudad de la luz. Sin embargo, un fin de semana en Par\u00eds es suficiente para sentir el famoso ambiente parisino. No se pierda el Museo del Louvre (cuidado, cierra los martes) con sus innumerables colecciones de pinturas y esculturas, testigos de nuestra historia. Despu\u00e9s del Louvre, recorra la avenida de los Campos El\u00edseos en direcci\u00f3n al Arco del Triunfo para dar un agradable paseo. Si le gusta ir de compras, dir\u00edjase directamente a las Galer\u00edas Lafayette, los mayores grandes almacenes de moda de la capital. Incluso si no le gusta ir de compras, no deje de visitar la azotea de la tienda para disfrutar de unas vistas inmejorables de Par\u00eds: \u00a1es gratis! <\/span><\/p><p><span style=\"font-weight: 400;\">Tras un hermoso paseo por el r\u00edo Sena, haga una parada en el rom\u00e1ntico restaurante \"Le Colima\u00e7on\" para degustar cocina tradicional francesa a buen precio. Antes de partir hacia Poitiers, deguste los famosos macarrones de \"La Dur\u00e9e\", \u00a1una sabrosa y bien guardada receta secreta!<\/span><\/p><h2 class=\"wp-block-heading\"><b>Poitiers, Francia<\/b><\/h2><p><span style=\"font-weight: 400;\">A s\u00f3lo 90 minutos de Par\u00eds en tren, Poitiers le invita a un viaje al coraz\u00f3n de la historia de Francia. El arte rom\u00e1nico est\u00e1 omnipresente en la ciudad: monumentos civiles y religiosos, callejuelas estrechas con casas de entramado de madera... un edificio clave de este testimonio arquitect\u00f3nico, la iglesia de Notre-Dame-la-Grande y su fachada con decoraci\u00f3n esculpida. El Palacio de los Condes de Poitou-ducs d'Aquitaine (hoy Palacio de Justicia), situado en el coraz\u00f3n de la ciudad, recuerda tambi\u00e9n el periodo de dominaci\u00f3n de la ciudad entre los siglos X y XII. <\/span><\/p><p><span style=\"font-weight: 400;\">Bautizada como la ciudad de los 100 campanarios, Poitiers no se duerme en los laureles. El parque de atracciones \"Futuroscope\" mira decididamente hacia el futuro con impresionantes atracciones dotadas de las \u00faltimas tecnolog\u00edas. No se pierda la atracci\u00f3n m\u00e1s reciente: un viaje alrededor del mundo inspirado en la novela de Julio Verne a bordo de una m\u00e1quina extraordinaria, \u00a1una experiencia incre\u00edble!<\/span><\/p><h2 class=\"wp-block-heading\"><b>Burdeos, Francia<\/b><\/h2><figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/05\/bordeaux-3876995_1280-1024x768.jpg\" alt=\"\" class=\"wp-image-1711\"\/><figcaption class=\"wp-element-caption\">Imagen de <a href=\"https:\/\/pixabay.com\/users\/stuthnagyniki-3920746\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=3876995\" target=\"_blank\" rel=\"noopener\">Niki Nagy<\/a> de <a href=\"https:\/\/pixabay.com\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=3876995\" target=\"_blank\" rel=\"noopener\">Pixabay<\/a><\/figcaption><\/figure><p><span style=\"font-weight: 400;\">Otros 80 minutos en tren y llegar\u00e1 a Burdeos, gracias al tren de alta velocidad TGV (aseg\u00farese de reservar asiento). Durante el viaje al sur de Francia, eche un vistazo a los numerosos vi\u00f1edos de vino que hacen que Burdeos sea famosa en todo el mundo. Nombrada \"la ciudad m\u00e1s de moda del mundo\" en 2017 por Lonely Planet, Burdeos es la ciudad de hoy, que combina arquitectura, cultura, gastronom\u00eda y arte de vivir. <\/span><\/p><p><span style=\"font-weight: 400;\">Para comenzar su visita, vaya a admirar el famoso espejo de agua: con una superficie de casi 3.500 m\u00b2, \u00a1es el m\u00e1s grande del mundo! A continuaci\u00f3n, dir\u00edjase directamente a la famosa Place de la Com\u00e9die, en pleno centro de la ciudad. Det\u00e9ngase ante el \"Grand Th\u00e9\u00e2tre\". Construido por orden del mariscal de Richelieu e inaugurado en 1780, el teatro bordel\u00e9s est\u00e1 considerado como uno de los m\u00e1s bellos del mundo. <\/span><\/p><p><span style=\"font-weight: 400;\">Tambi\u00e9n debe visitar la flamante \"Cit\u00e9 du Vin\", inaugurada en 2016, que le ofrece un viaje inmersivo y sensorial muy singular. Para llegar a ella, camine por los muelles reci\u00e9n renovados que bordean el r\u00edo Garona. Por el camino, ver\u00e1s algunos edificios clasificados como Patrimonio de la Humanidad por la UNESCO. <\/span><\/p><p><span style=\"font-weight: 400;\">Para cenar, le recomendamos el \"Bistrot d' Aur\u00e9lie\" o el \"Au Bistrot \" - excelentes precios para una sabrosa y gastron\u00f3mica comida francesa. Antes de partir hacia Biarritz, pruebe los famosos \"cannel\u00e9s\", aromatizados con ron y vainilla.<\/span><\/p><h2 class=\"wp-block-heading\"><b>Biarritz, Francia<\/b><\/h2><figure class=\"wp-block-image alignnone wp-image-1520 size-large\"><img decoding=\"async\" src=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2018\/01\/photo-1535910151436-47287d5a4d92-1024x683.jpeg\" alt=\"Interrail en Francia - Biarritz\" class=\"wp-image-1520\"\/><figcaption class=\"wp-element-caption\">Surfistas en Biarritz (Cr\u00e9dito: Mauro Paillex)<\/figcaption><\/figure><p><span style=\"font-weight: 400;\">Entre oc\u00e9ano y monta\u00f1a, muy cerca del Pa\u00eds Vasco y pr\u00f3xima a Espa\u00f1a, la ciudad de Biarritz es ideal para hacer excursiones. Tambi\u00e9n es conocida por ser la capital europea del surf, con importantes olas durante todo el a\u00f1o. La cultura del surf se respira en toda la ciudad, especialmente en la \"Cit\u00e9 de l'Oc\u00e9an\" y en el gran n\u00famero de tiendas de surf y empresas de alquiler de tablas que hay en la zona. Si nunca ha practicado surf, ha venido al lugar adecuado (\u00a1hay 18 escuelas de surf!). En Biarritz le esperan 6 playas, cada una con su encanto. La m\u00e1s conocida y apreciada por los surfistas es la playa \"de la c\u00f4te des Basques\". <\/span><\/p><p><span style=\"font-weight: 400;\">Si el surf no es lo suyo, eche un vistazo a la arquitectura tan t\u00edpica de las casas antiguas del centro de la ciudad. Aproveche para visitar las famosas \"Halles de Biarritz\", que albergan a m\u00e1s de 120 comerciantes. Descubrir\u00e1 la gastronom\u00eda local, como \"le g\u00e2teau Basque\" o \"le jambon de Bayonne\". <\/span><\/p><p><span style=\"font-weight: 400;\">Para alojarse, le recomendamos el \"albergue juvenil HI Biarritz\", un lugar muy agradable y acogedor. Ahora, \u00a1en ruta hacia Toulouse!<\/span><\/p><h2 class=\"wp-block-heading\"><b>Toulouse, Francia<\/b><\/h2><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2023\/02\/dat-vo-F4u8Vm7UdgY-unsplash-1024x683.jpg\" alt=\"\" class=\"wp-image-4285\"\/><figcaption class=\"wp-element-caption\">Gente disfrutando de la puesta de sol en el r\u00edo Garona (Cr\u00e9d: \u00a0<a href=\"https:\/\/unsplash.com\/@hoangdat302?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener\">DAT VO<\/a>\u00a0en\u00a0<a href=\"https:\/\/unsplash.com\/photos\/F4u8Vm7UdgY?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\" target=\"_blank\" rel=\"noopener\">Unsplash<\/a>)<\/figcaption><\/figure><\/div><p><span style=\"font-weight: 400;\">Bienvenido a la capital del suroeste de Francia. Toulouse es una ciudad llena de color, con sus fachadas de ladrillo rosa y su flor emblem\u00e1tica, la Violeta. A medio camino entre el mar Mediterr\u00e1neo y el oc\u00e9ano Atl\u00e1ntico, la \"Ciudad Rosa\", como la llaman, fusiona alegremente patrimonio y \"art de vivre\". Comience su visita en la \"place du Capitole\", un espacio abierto en el centro hist\u00f3rico, apto para peatones. Con una superficie de m\u00e1s de 12.000 m\u00b2, \u00a1tan grande como dos campos de f\u00fatbol! De arquitectura neocl\u00e1sica, el Capitole alberga el ayuntamiento de Toulouse (visita gratuita), as\u00ed como un teatro y una orquesta nacional que merecen una visita. No lejos de la plaza se encuentra el Monasterio de los Jacobinos. Construido a partir del siglo XIII, el Monasterio de los Jacobinos es un magn\u00edfico edificio religioso g\u00f3tico, conocido por albergar las reliquias de Santo Tom\u00e1s de Aquino. <\/span><\/p><p><span style=\"font-weight: 400;\">En cuanto a la comida, el centro de la ciudad est\u00e1 lleno de excelentes restaurantes donde degustar la cocina tradicional local: pato, \"foie gras\" o \"cassoulet\". Cuidado, la comida es deliciosa, pero tambi\u00e9n un poco pesada. No olvide dar un paseo nocturno por las orillas del r\u00edo Garona. <\/span><\/p><p><span style=\"font-weight: 400;\">Por \u00faltimo, si le interesa la aeron\u00e1utica, visite la Ciudad del Espacio para saltar a la luna... \u00a1en 3D! Es hora de coger el tren hacia Montpellier.<\/span><\/p><h2 class=\"wp-block-heading\"><b>Montpellier, Francia<\/b><\/h2><figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/05\/montpellier-913011_1280-1024x682.jpg\" alt=\"\" class=\"wp-image-1712\" srcset=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/05\/montpellier-913011_1280-1024x682.jpg 1024w, https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/05\/montpellier-913011_1280-600x400.jpg 600w, https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/05\/montpellier-913011_1280-300x200.jpg 300w, https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/05\/montpellier-913011_1280-768x512.jpg 768w, https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2020\/05\/montpellier-913011_1280.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagen de <a href=\"https:\/\/pixabay.com\/users\/ennelise-629138\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=913011\" target=\"_blank\" rel=\"noopener\">Ennelise Napoleoni-Bianco<\/a> de <a href=\"https:\/\/pixabay.com\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=913011\" target=\"_blank\" rel=\"noopener\">Pixabay<\/a><\/figcaption><\/figure><p><span style=\"font-weight: 400;\">Tras 2 horas y 20 minutos en tren, llegar\u00e1 a Montpellier. Esta ciudad, cercana al mar Mediterr\u00e1neo, seduce tanto a estudiantes como a amantes de las calles ins\u00f3litas y la vida nocturna. Montpellier es, en cualquier \u00e9poca del a\u00f1o, la ciudad m\u00e1s atractiva del sur de Francia. El clima es agradable todo el a\u00f1o. El centro hist\u00f3rico de Montpellier, rico en una historia milenaria, destaca por sus calles peatonales adoquinadas, sus originales tiendas conceptuales y sus variados restaurantes. <\/span><\/p><p><span style=\"font-weight: 400;\">La \"Place de la Com\u00e9die\" atraer\u00e1 inevitablemente su atenci\u00f3n. Completamente peatonal, la plaza est\u00e1 repleta de terrazas que le permitir\u00e1n disfrutar de un caf\u00e9 o un aperitivo mientras contempla la famosa \u00f3pera Com\u00e9die, inspirada en la \u00d3pera Garnier de Par\u00eds. Si tiene tiempo, explore tambi\u00e9n la zona hist\u00f3rica del Ecusson. La mejor manera de conocer las calles medievales de Montpellier es dejar el mapa en el bolsillo y dejarse guiar por la curiosidad. Admire tambi\u00e9n el Arco del Triunfo. Este monumento de 15 metros, que constituye la puerta de entrada al casco antiguo de Montpellier, fue construido en 1691 en honor de Luis XIV. Antes de partir hacia Marsella, t\u00f3mese uno de los famosos c\u00f3cteles en \"Papa Doble\", y despu\u00e9s disfrute de una sabrosa hamburguesa en \"Burger et Blanquette\".<\/span><\/p><h2 class=\"wp-block-heading\"><b>Marsella, Francia<\/b><\/h2><figure class=\"wp-block-image alignnone wp-image-1530 size-large\"><img decoding=\"async\" src=\"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2018\/01\/photo-1576244348464-c7d393b6dfc0-1024x665.jpeg\" alt=\"\" class=\"wp-image-1530\"\/><figcaption class=\"wp-element-caption\">Vista de Marsella con la Bas\u00edlica de Notre-Dame-de-la-Garde al fondo (Cr\u00e9dito: <a href=\"https:\/\/unsplash.com\/@florianwehde\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">Florian Wehde<\/a>)<\/figcaption><\/figure><p><span style=\"font-weight: 400;\">La \u00faltima parada de nuestro viaje es la m\u00edtica ciudad de Marsella, conocida en todo el mundo por su equipo de f\u00fatbol, el Olympique de Marseille. Para empezar, dir\u00edjase al viejo puerto de Marsella y si\u00e9ntese en uno de los muchos bares para disfrutar del pastis, la bebida alcoh\u00f3lica tradicional de la ciudad. Mientras se relaja con una copa en la mano, levante la vista y observe el animado puerto que nunca duerme, donde marineros, lugare\u00f1os y turistas se cruzan constantemente. A continuaci\u00f3n, explore el barrio m\u00e1s de moda de Marsella, \"le quartier du Panier\", fundado hace 2.600 a\u00f1os por los griegos. Hoy en d\u00eda, el barrio es un punto de referencia para los artistas, gracias a la presencia de numerosas galer\u00edas de arte. <\/span><\/p><p><span style=\"font-weight: 400;\">Los amantes de la buena comida tambi\u00e9n estar\u00e1n encantados con la incre\u00edble gastronom\u00eda del distrito. Por \u00faltimo, pero no menos importante, los hipsters tambi\u00e9n estar\u00e1n encantados con todas las boutiques vintage. \u00bfBusca un lugar donde hacerse la foto perfecta para Instagram? Sube a la Bas\u00edlica de Notre-Dame-de-la-Garde (pero, prep\u00e1rate para una buena hora de caminata). Cuando est\u00e9s en la cima, ser\u00e1s recompensado con una gran vista sobre la ciudad bajo un sol radiante.<\/span><\/p><p><span style=\"font-weight: 400;\">Y as\u00ed termina nuestro viaje en Interrail, \u00a1\"au revoir la France\"!<\/span><\/p><p><i>Si quieres seguir la ruta Interrail definitiva de Arnaud por Francia, puedes empezar con esto <a href=\"https:\/\/interrailplanner.com\/plan\/35940\/\">Plantilla de ruta Interrail<\/a>.<\/i><\/p><p><em><span style=\"font-weight: 400;\">\u00bfQuiere pasar unos d\u00edas m\u00e1s en Francia y explorar otros lugares?<\/span><\/em><\/p><p><em><span style=\"font-weight: 400;\">Arnaud recomienda visitar Saint-Tropez, Cannes y Niza, con su famoso \"promenade des anglais\". Estas tres ciudades dan fama mundial a la Costa Azul.<\/span><\/em><\/p><div class=\"inter-after-content\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-1680602691\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"8015293915\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Arnaud Schuffenecker, orgulloso franc\u00e9s, nos gu\u00eda por sus lugares favoritos de Francia. Si quiere hacer interrail por Francia, siga la ruta Interrail definitiva de Arnaud por Francia con esta plantilla de ruta Interrail. \u00bfTiene pensado viajar a Francia? \"Cocorico\". Es el destino tur\u00edstico m\u00e1s visitado del mundo, ofrece paisajes muy variados y...<\/p>","protected":false},"author":12,"featured_media":590,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13,5,8],"tags":[32,46],"class_list":["post-297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interrail-country-region-guides","category-european-travel-guides","category-interrail-routes","tag-interrail-france","tag-interrail-paris"],"cc_featured_image_caption":{"caption_text":"","source_text":"Credit: freetoedit images","source_url":"https:\/\/picsart.com\/i\/image-start-your-292148227022201"},"jetpack_featured_media_url":"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2019\/08\/interrail-france.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/posts\/297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=297"}],"version-history":[{"count":0,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/posts\/297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/media\/590"}],"wp:attachment":[{"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}