
{"id":172,"date":"2016-07-12T18:39:15","date_gmt":"2016-07-12T17:39:15","guid":{"rendered":"https:\/\/209.222.30.173\/?p=172"},"modified":"2020-12-22T14:11:00","modified_gmt":"2020-12-22T14:11:00","slug":"an-interrail-adventure-blog-9-zurich","status":"publish","type":"post","link":"https:\/\/interrailplanner.com\/blog\/es\/una-aventura-interrail-blog-9-zurich\/","title":{"rendered":"Una aventura Interrail - Blog 9: Z\u00farich"},"content":{"rendered":"<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cuando uno viaja en tren por Europa, al igual que en casa, no puede elegir a sus compa\u00f1eros de viaje. Digo esto porque, en el momento de escribir estas l\u00edneas, estoy sentado enfrente de un ni\u00f1o muy parlanch\u00edn y su familia. Sin embargo, este viaje a Stuttgart es m\u00e1s corto (s\u00f3lo 3 horas), as\u00ed que quiz\u00e1 mi paciencia aguante. Mientras tanto, puedo consolarme cont\u00e1ndoles mi estancia en Z\u00farich.<\/span><\/p><div class=\"inter-content-paragraph\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-2843840706\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Cuando baj\u00e9 del tren a Z\u00farich y me dirig\u00ed al albergue, me rondaba por la cabeza una pregunta: \u00bfse puede nadar aqu\u00ed? Digo esto porque la \u00faltima parte de mi viaje en tren hasta Z\u00farich discurri\u00f3 junto al lago del que Z\u00farich es uno de sus extremos, el Zurichsee. Una hora m\u00e1s tarde, acompa\u00f1\u00e9 a un chico del albergue hasta una playa de guijarros y mi pregunta qued\u00f3 resuelta. Aunque el agua estaba bastante fr\u00eda, la vista desde el interior del lago de agua dulce era asombrosa. Por un lado se ve\u00edan los Alpes a lo lejos y por el otro el paisaje urbano de Z\u00farich. Nadar tambi\u00e9n significaba que hab\u00eda completado las tres actividades del triatl\u00f3n; las otras dos eran correr para coger el tren y dar la vuelta a Liechtenstein en bicicleta.<\/span><\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/TcPgnDcr1gl5MWUioBqf8yghWEPoxfEzAhqkR69IF4dCBih6-7MjYDU_NPXLE9dGw89OkwUsY8q1iQ7NC67CnS0csHnnCGucJ5ZrNcSWFxQh2G3sAdPbaGT2pj6B1_E2LW9Zt-Pc\" alt=\"\" width=\"1600\" height=\"900\"><figcaption class=\"wp-caption-text\">La zona de ba\u00f1o del lago<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">A la ma\u00f1ana siguiente volv\u00ed a hacer un recorrido a pie, ya que no lo hac\u00eda desde Zagreb. Se centr\u00f3 en las zonas m\u00e1s antiguas de Z\u00farich, sobre todo las iglesias y el casco antiguo. Durante la visita me puse a charlar con dos interraileros irlandeses, as\u00ed que despu\u00e9s nos fuimos a dar un paseo y a relajarnos junto al lago. Por la tarde nos separamos y me fui a conocer Z\u00farich Oeste, una zona supuestamente remodelada y de moda. Aunque era interesante, lo que m\u00e1s recuerdo es haber descubierto un plat\u00f3 de cine. Caminaba por una calle, cuando vi a unas personas de pie en un edificio con grandes luces, portapapeles y en otra parte hab\u00eda una c\u00e1mara. Lo m\u00e1s surrealista fue ver a un hombre que llevaba a una vaca mugiendo con una cuerda por las calles de Z\u00farich. Consegu\u00ed hacerle una foto lejana, \u00a1si no me creen!<\/span><\/p><div class=\"inter-content_2\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-2159178396\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"7158573474\" \ndata-ad-layout=\"in-article\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<figure style=\"width: 718px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/I_xRMul5z7o9ttIF3CKxAffNFegN6tHodSc2SPC0JFvvyN_Ro3E9RoB87bAXPzcTV6QLISZ7OsGzNbn6CjypVQBkQQnKAyfySmcpr07zl7E2NmnjVWpv_0VNFYKDdOwFBUIFooqV\" alt=\"\" width=\"718\" height=\"391\"><figcaption class=\"wp-caption-text\">\u00bfUna pel\u00edcula sobre vacas que viven en bloques de pisos?<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">M\u00e1s tarde, ese mismo d\u00eda, hice una excursi\u00f3n, una especie de peregrinaci\u00f3n, a la chocolater\u00eda Lindt de Z\u00farich. Situada junto a la f\u00e1brica de chocolate Lindt, era una especie de para\u00edso para los amantes del chocolate. Nada m\u00e1s salir de la f\u00e1brica se pod\u00eda oler el chocolate en el aire. Al entrar en la tienda te recib\u00edan con chocolate gratis y hab\u00eda degustaciones por todas partes, adem\u00e1s de bombones Lindt que nunca hab\u00eda visto antes, algunos de los cuales s\u00f3lo se vend\u00edan en la tienda. Me asegur\u00e9 de no irme con las manos vac\u00edas y compr\u00e9 un par de tabletas de chocolate de la \"edici\u00f3n de verano\", aunque otra cosa es si llegar\u00e1n a Inglaterra o no.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Esa noche me reun\u00ed con los viajeros irlandeses para darme un chapuz\u00f3n en el lago, que cerca de la puesta de sol se convirti\u00f3 en una experiencia un poco fr\u00eda. El ambiente en el lago era muy relajado, con varios grupos de gente haciendo barbacoas, tomando algo y disfrutando de la compa\u00f1\u00eda de los dem\u00e1s. Sin embargo, al final se puso el sol y, tras deambular por el centro de la ciudad durante una o dos horas, los tres nos separamos por \u00faltima vez.<\/span><\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/WMC-JuZ1YJFXx1Q4w6QEHyD76ODRtGkO7Y_z-98JhZchsq3R8OVDmTgSUZ98oxey2WaX3w_7HjdLWLFLcDjZA-gPeLFbA9amVdg0weJs6BKiuBH9rE7Q17VqxWyMvO1A5My2yGyg\" alt=\"\" width=\"1600\" height=\"900\"><figcaption class=\"wp-caption-text\">Puesta de sol junto al lago de Z\u00farich<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Esta ma\u00f1ana la hemos pasado paseando por la ciudad de Z\u00farich, el lago y, finalmente, la estaci\u00f3n de tren. Como te estar\u00e1s preguntando, la ruidosa familia sigue aqu\u00ed. Pero no hay de qu\u00e9 preocuparse, s\u00f3lo queda una hora...<\/span><\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/twitter.com\/jackmanjames26\" target=\"_blank\" rel=\"noopener\"><i>James Jackman<\/i><\/a><i> compartir\u00e1 historias de su viaje en Interrail cada pocos d\u00edas a lo largo de junio y julio - s\u00edganos en&nbsp;<\/i><a href=\"https:\/\/www.facebook.com\/interrailplanner\/\" target=\"_blank\" rel=\"noopener\"><i>Facebook<\/i><\/a><i> y&nbsp;<\/i><a href=\"https:\/\/twitter.com\/planinterrail\" target=\"_blank\" rel=\"noopener\"><i>Twitter<\/i><\/a><i> para estar al tanto de sus actualizaciones en cuanto se publiquen.<\/i><\/p>\n<div class=\"inter-after-content\" style=\"margin-top: 20px;margin-bottom: 20px;\" id=\"inter-2333466308\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4633244982126279\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4633244982126279\" \ndata-ad-slot=\"8015293915\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Cuando uno viaja en tren por Europa, al igual que en casa, no puede elegir a sus compa\u00f1eros de viaje. Digo esto porque, en el momento de escribir estas l\u00edneas, estoy sentado enfrente de un ni\u00f1o muy parlanch\u00edn y su familia. Sin embargo, este viaje a Stuttgart es m\u00e1s corto (s\u00f3lo 3 horas), as\u00ed que quiz\u00e1 mi paciencia aguante...<\/p>","protected":false},"author":6,"featured_media":618,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[59,65],"class_list":["post-172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interrail-adventures","tag-interrail-switzerland","tag-interrail-zurich"],"cc_featured_image_caption":{"caption_text":false,"source_text":false,"source_url":false},"jetpack_featured_media_url":"https:\/\/interrailplanner.com\/blog\/wp-content\/uploads\/2019\/08\/interrail-adventure-zurich.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":0,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/media\/618"}],"wp:attachment":[{"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interrailplanner.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}